{"id":196,"date":"2019-01-09T07:57:55","date_gmt":"2019-01-09T06:57:55","guid":{"rendered":"http:\/\/localhost\/projects\/"},"modified":"2019-01-09T07:57:55","modified_gmt":"2019-01-09T06:57:55","slug":"projects","status":"publish","type":"page","link":"https:\/\/bricolos.ma\/fr\/projects\/","title":{"rendered":"Projets"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"196\" class=\"elementor elementor-196\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"aux-parallax-section elementor-element elementor-element-9fdd512 e-flex e-con-boxed e-con e-parent\" data-id=\"9fdd512\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f9ae88 aux-appear-watch-animation aux-fade-in-right elementor-widget__width-inherit elementor-widget elementor-widget-aux_modern_heading\" data-id=\"1f9ae88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\"><\/h2><h3 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-before\">portfolio<\/span><\/h3><div class=\"aux-modern-heading-divider\"><\/div><div class=\"aux-modern-heading-description\"><p>Case Solution<\/p><\/div><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df3be14 elementor-widget__width-inherit elementor-widget elementor-widget-aux_recent_portfolios_tile\" data-id=\"df3be14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_recent_portfolios_tile.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-recent-portfolios aux-parent-auaaa34115\"><div class=\"aux-filters aux-togglable aux-overlay aux-underline-anim aux-right aux-isotope-filters\"><div class=\"aux-select-overlay\"><\/div><ul><li data-filter=\"all\" data-category-id=\"all\"><a href=\"#\"><span data-select=\"All\">All<\/span><\/a><\/li><li data-filter=\"construction\" data-category-id=\"5\" ><a href=\"#\"><span data-select=\"Construction\">Construction<\/span><\/a><\/li><li data-filter=\"electricity\" data-category-id=\"8\" ><a href=\"#\"><span data-select=\"Electricity\">Electricity<\/span><\/a><\/li><li data-filter=\"modern-kitchen\" data-category-id=\"3\" ><a href=\"#\"><span data-select=\"Modern Kitchen\">Modern Kitchen<\/span><\/a><\/li><li data-filter=\"paint\" data-category-id=\"49\" ><a href=\"#\"><span data-select=\"paint\">paint<\/span><\/a><\/li><li data-filter=\"renovation\" data-category-id=\"6\" ><a href=\"#\"><span data-select=\"Renovation\">Renovation<\/span><\/a><\/li><\/ul><\/div><div id=\"6a98177e2d9c9\" data-element-id=\"auaaa34115\" class=\"aux-portfolio-columns aux-ajax-view aux-isotope-animated aux-tiles-layout aux-lightbox-gallery\" data-lazyload=\"true\" data-space=\"0\" data-pagination=\"true\" data-deeplink=\"false\" data-slug=\"\" data-perpage=\"11\" data-layout=\"packery\" data-reveal-transition-duration=\"600\" data-reveal-between-delay=\"60\" data-hide-transition-duration=\"600\" data-hide-between-delay=\"30\" data-num=\"12\" data-order=\"DESC\" data-orderby=\"date\" data-taxonomy=\"portfolio-cat\" data-n=\"5188a16080\"><div class=\"aux-items-loading aux-loading-hide\"><div class=\"aux-loading-loop\"><svg class=\"aux-circle\" width=\"100%\" height=\"100%\" viewBox=\"0 0 42 42\"><circle class=\"aux-stroke-bg\" r=\"20\" cx=\"21\" cy=\"21\" fill=\"none\"><\/circle><circle class=\"aux-progress\" r=\"20\" cx=\"21\" cy=\"21\" fill=\"none\" transform=\"rotate(-90 21 21)\"><\/circle><\/svg><\/div><\/div><div class=\"aux-iso-item aux-loading aux-tile-6-6 aux-t-tile-12-12 aux-m-tile-12-12 paint\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-486 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-paint portfolio-tag-paint-house portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-darken \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/house-painting-services\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/paint-house-1000x1000.jpg\" class=\"aux-attachment aux-featured-image attachment-1000x1000 aux-attachment-id-488 \" alt=\"paint house\" srcset=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/paint-house-150x150.jpg 150w,https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/paint-house-300x300.jpg 300w,https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/paint-house-768x768.jpg 768w,https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/paint-house-1024x1024.jpg 1024w,https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/paint-house-1000x1000.jpg 1000w,https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/paint-house-1070x1070.jpg 1070w\" data-ratio=\"1\" data-original-w=\"1080\" sizes=\"(max-width:479px) 480px,(max-width:767px) 768px,(max-width:1023px) 1024px,1000px\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/paint-house.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1080\" data-original-height = \"1080\" data-caption = \"paint house\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/house-painting-services\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/house-painting-services\/\">\n                                                House Painting Services                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/bricolos.ma\/fr\/portfolio-cat\/paint\/\" title=\"View all posts in paint\" rel=\"category\" >paint<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-tile-3-3 aux-t-tile-6-6 aux-m-tile-6-6 electricity\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-479 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-electricity portfolio-tag-electricity portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-darken \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/electricity\/\"><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/20240219_143800-scaled-500x500.jpg\" class=\"aux-attachment aux-featured-image attachment-500x500 aux-attachment-id-565 \" alt=\"20240219_143800\" srcset=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/20240219_143800-scaled-150x150.jpg 150w,https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/20240219_143800-scaled-300x300.jpg 300w,https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/20240219_143800-scaled-768x768.jpg 768w,https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/20240219_143800-scaled-1024x1024.jpg 1024w,https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/20240219_143800-scaled-500x500.jpg 500w,https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/20240219_143800-scaled-1910x1910.jpg 1910w\" data-ratio=\"1\" data-original-w=\"1920\" sizes=\"(max-width:479px) 480px,(max-width:767px) 768px,(max-width:1023px) 1024px,500px\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/20240219_143800-scaled.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1920\" data-original-height = \"2560\" data-caption = \"20240219_143800\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/electricity\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/electricity\/\">\n                                                Electricity                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/bricolos.ma\/fr\/portfolio-cat\/electricity\/\" title=\"View all posts in Electricity\" rel=\"category\" >Electricity<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-tile-3-3 aux-t-tile-6-6 aux-m-tile-6-6 construction\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-165 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-construction portfolio-tag-construction portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-darken \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/principle-of-product-design\/\"><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction1-500x500.jpg\" class=\"aux-attachment aux-featured-image attachment-500x500 aux-attachment-id-332 \" alt=\"Construction[1]\" srcset=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction1-150x150.jpg 150w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction1-300x300.jpg 300w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction1-768x768.jpg 768w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction1-1024x1024.jpg 1024w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction1-500x500.jpg 500w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction1-1070x1070.jpg 1070w\" data-ratio=\"1\" data-original-w=\"1080\" sizes=\"(max-width:479px) 480px,(max-width:767px) 768px,(max-width:1023px) 1024px,500px\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction1.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1080\" data-original-height = \"1080\" data-caption = \"Construction[1]\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/principle-of-product-design\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/principle-of-product-design\/\">\n                                                House Construction Project \u2013 Fez                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/bricolos.ma\/fr\/portfolio-cat\/construction\/\" title=\"View all posts in Construction\" rel=\"category\" >Construction<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-tile-3-3 aux-t-tile-6-6 aux-m-tile-6-6 modern-kitchen\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-168 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-modern-kitchen portfolio-tag-cuisine portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-darken \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/office-building\/\"><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"397\" src=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Cuisine_Moderne_Sur_Mesure1-500x500.jpg\" class=\"aux-attachment aux-featured-image attachment-370x397 aux-attachment-id-360 \" alt=\"Cuisine_Moderne_Sur_Mesure[1]\" srcset=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Cuisine_Moderne_Sur_Mesure1-150x150.jpg 150w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Cuisine_Moderne_Sur_Mesure1-300x300.jpg 300w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Cuisine_Moderne_Sur_Mesure1-500x500.jpg 370w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Cuisine_Moderne_Sur_Mesure1-360x360.jpg 360w\" data-ratio=\"1\" data-original-w=\"370\" sizes=\"(max-width:479px) 480px,(max-width:767px) 768px,(max-width:1023px) 1024px,370px\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Cuisine_Moderne_Sur_Mesure1.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"370\" data-original-height = \"397\" data-caption = \"Cuisine_Moderne_Sur_Mesure[1]\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/office-building\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/office-building\/\">\n                                                Modern Kitchens                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/bricolos.ma\/fr\/portfolio-cat\/modern-kitchen\/\" title=\"View all posts in Modern Kitchen\" rel=\"category\" >Modern Kitchen<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-tile-3-3 aux-t-tile-6-6 aux-m-tile-6-6 renovation\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-170 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-renovation portfolio-tag-renovation portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-darken \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/construction\/\"><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"397\" src=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction-villa-\u2013-Fes-500x500.jpg\" class=\"aux-attachment aux-featured-image attachment-370x397 aux-attachment-id-351 \" alt=\"Construction villa \u2013 F\u00e8s\" srcset=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction-villa-\u2013-Fes-150x150.jpg 150w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction-villa-\u2013-Fes-300x300.jpg 300w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction-villa-\u2013-Fes-500x500.jpg 370w,https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction-villa-\u2013-Fes-360x360.jpg 360w\" data-ratio=\"1\" data-original-w=\"370\" sizes=\"(max-width:479px) 480px,(max-width:767px) 768px,(max-width:1023px) 1024px,370px\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/bricolos.ma\/wp-content\/uploads\/2019\/01\/Construction-villa-\u2013-Fes.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"370\" data-original-height = \"397\" data-caption = \"Construction villa \u2013 F\u00e8s\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/construction\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/bricolos.ma\/fr\/portfolio\/construction\/\">\n                                                Renovation                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/bricolos.ma\/fr\/portfolio-cat\/renovation\/\" title=\"View all posts in Renovation\" rel=\"category\" >Renovation<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><\/div><script type=\"text\/javascript\">var auaaa34115AjaxConfig = {\"title\":\"\",\"cat\":[],\"num\":\"12\",\"only_posts__in\":\"\",\"include\":\"\",\"exclude\":\"\",\"posts_per_page\":-1,\"offset\":\"\",\"order_by\":\"date\",\"order\":\"DESC\",\"exclude_without_media\":\"yes\",\"display_like\":false,\"deeplink\":\"\",\"use_ajax\":\"\",\"deeplink_slug\":null,\"show_filters\":\"yes\",\"filter_by\":\"portfolio-cat\",\"filter_style\":\"aux-overlay aux-underline-anim\",\"filter_align\":\"aux-right\",\"reveal_transition_duration\":\"600\",\"reveal_between_delay\":\"60\",\"hide_transition_duration\":\"600\",\"hide_between_delay\":\"30\",\"item_style\":\"classic\",\"tile_style_pattern\":\"default\",\"tiles_item_style\":\"overlay-lightbox\",\"entry_background_color\":\"\",\"entry_border_color\":\"\",\"paginate\":\"yes\",\"perpage\":\"11\",\"crop\":true,\"display_title\":\"yes\",\"show_info\":\"yes\",\"display_read_more\":false,\"image_aspect_ratio\":0.75,\"space\":30,\"desktop_cnum\":4,\"tablet_cnum\":\"inherit\",\"phone_cnum\":\"1\",\"layout\":\"tiles\",\"tag\":\"\",\"filter\":\"\",\"extra_classes\":\"\",\"extra_column_classes\":\"\",\"custom_el_id\":\"\",\"template_part_file\":\"recent-portfolio\",\"extra_template_path\":\"\\\/home\\\/u824036565\\\/domains\\\/bricolos.ma\\\/public_html\\\/wp-content\\\/plugins\\\/auxin-portfolio\\\/public\\\/templates\\\/elements\",\"universal_id\":\"auaaa34115\",\"query_args\":[],\"term\":\"\",\"reset_query\":true,\"use_wp_query\":false,\"wp_query_args\":[],\"custom_wp_query\":\"\",\"loadmore_type\":null,\"loadmore_label\":null,\"loadmore_per_page\":\"12\",\"term_field\":\"slug\",\"base\":\"aux_recent_portfolios_grid\",\"base_class\":\"aux-widget-recent-portfolios\",\"paged\":\"\",\"override_global_query\":false,\"content\":null,\"skip_wrappers\":false,\"content_width\":2000,\"inview_transition\":\"none\",\"inview_duration\":\"\",\"inview_delay\":\"\",\"inview_repeat\":\"no\",\"inview_offset\":\"\",\"called_from\":\"\"};<\/script><\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>portfolio Case Solution All Construction Garden House School Principle Of Product Design Construction Garden Garden School School Office Building House Garden Garden Construction Construction School School Garden Garden House House Garden Garden House House<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/page-builder-content.php","meta":{"footnotes":""},"class_list":["post-196","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projects - Bricolos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bricolos.ma\/fr\/projects\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - Bricolos\" \/>\n<meta property=\"og:description\" content=\"portfolio Case Solution All Construction Garden House School Principle Of Product Design Construction Garden Garden School School Office Building House Garden Garden Construction Construction School School Garden Garden House House Garden Garden House House\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bricolos.ma\/fr\/projects\/\" \/>\n<meta property=\"og:site_name\" content=\"Bricolos\" \/>\n<meta property=\"og:image\" content=\"https:\/\/demo.phlox.pro\/construction\/wp-content\/uploads\/sites\/87\/2019\/01\/joel-filipe-166058-unsplash-1000x1000.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bricolos.ma\\\/projects\\\/\",\"url\":\"https:\\\/\\\/bricolos.ma\\\/projects\\\/\",\"name\":\"Projects - Bricolos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bricolos.ma\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bricolos.ma\\\/projects\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bricolos.ma\\\/projects\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/demo.phlox.pro\\\/construction\\\/wp-content\\\/uploads\\\/sites\\\/87\\\/2019\\\/01\\\/joel-filipe-166058-unsplash-1000x1000.jpg\",\"datePublished\":\"2019-01-09T06:57:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bricolos.ma\\\/projects\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bricolos.ma\\\/projects\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bricolos.ma\\\/projects\\\/#primaryimage\",\"url\":\"https:\\\/\\\/demo.phlox.pro\\\/construction\\\/wp-content\\\/uploads\\\/sites\\\/87\\\/2019\\\/01\\\/joel-filipe-166058-unsplash-1000x1000.jpg\",\"contentUrl\":\"https:\\\/\\\/demo.phlox.pro\\\/construction\\\/wp-content\\\/uploads\\\/sites\\\/87\\\/2019\\\/01\\\/joel-filipe-166058-unsplash-1000x1000.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bricolos.ma\\\/projects\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/bricolos.ma\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bricolos.ma\\\/#website\",\"url\":\"https:\\\/\\\/bricolos.ma\\\/\",\"name\":\"Bricolos\",\"description\":\"Complete Elementor Demo - Phlox WordPress Theme\",\"publisher\":{\"@id\":\"https:\\\/\\\/bricolos.ma\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bricolos.ma\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bricolos.ma\\\/#organization\",\"name\":\"Bricolos\",\"url\":\"https:\\\/\\\/bricolos.ma\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bricolos.ma\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bricolos.ma\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cropped-logo-Bricolospng-2.png\",\"contentUrl\":\"https:\\\/\\\/bricolos.ma\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cropped-logo-Bricolospng-2.png\",\"width\":237,\"height\":40,\"caption\":\"Bricolos\"},\"image\":{\"@id\":\"https:\\\/\\\/bricolos.ma\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projects - Bricolos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bricolos.ma\/fr\/projects\/","og_locale":"fr_FR","og_type":"article","og_title":"Projects - Bricolos","og_description":"portfolio Case Solution All Construction Garden House School Principle Of Product Design Construction Garden Garden School School Office Building House Garden Garden Construction Construction School School Garden Garden House House Garden Garden House House","og_url":"https:\/\/bricolos.ma\/fr\/projects\/","og_site_name":"Bricolos","og_image":[{"url":"https:\/\/demo.phlox.pro\/construction\/wp-content\/uploads\/sites\/87\/2019\/01\/joel-filipe-166058-unsplash-1000x1000.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bricolos.ma\/projects\/","url":"https:\/\/bricolos.ma\/projects\/","name":"Projects - Bricolos","isPartOf":{"@id":"https:\/\/bricolos.ma\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bricolos.ma\/projects\/#primaryimage"},"image":{"@id":"https:\/\/bricolos.ma\/projects\/#primaryimage"},"thumbnailUrl":"https:\/\/demo.phlox.pro\/construction\/wp-content\/uploads\/sites\/87\/2019\/01\/joel-filipe-166058-unsplash-1000x1000.jpg","datePublished":"2019-01-09T06:57:55+00:00","breadcrumb":{"@id":"https:\/\/bricolos.ma\/projects\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bricolos.ma\/projects\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bricolos.ma\/projects\/#primaryimage","url":"https:\/\/demo.phlox.pro\/construction\/wp-content\/uploads\/sites\/87\/2019\/01\/joel-filipe-166058-unsplash-1000x1000.jpg","contentUrl":"https:\/\/demo.phlox.pro\/construction\/wp-content\/uploads\/sites\/87\/2019\/01\/joel-filipe-166058-unsplash-1000x1000.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/bricolos.ma\/projects\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bricolos.ma\/"},{"@type":"ListItem","position":2,"name":"Projects"}]},{"@type":"WebSite","@id":"https:\/\/bricolos.ma\/#website","url":"https:\/\/bricolos.ma\/","name":"Bricolos","description":"Complete Elementor Demo - Phlox WordPress Theme","publisher":{"@id":"https:\/\/bricolos.ma\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bricolos.ma\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bricolos.ma\/#organization","name":"Bricolos","url":"https:\/\/bricolos.ma\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bricolos.ma\/#\/schema\/logo\/image\/","url":"https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/cropped-logo-Bricolospng-2.png","contentUrl":"https:\/\/bricolos.ma\/wp-content\/uploads\/2026\/04\/cropped-logo-Bricolospng-2.png","width":237,"height":40,"caption":"Bricolos"},"image":{"@id":"https:\/\/bricolos.ma\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bricolos.ma\/fr\/wp-json\/wp\/v2\/pages\/196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bricolos.ma\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bricolos.ma\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bricolos.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bricolos.ma\/fr\/wp-json\/wp\/v2\/comments?post=196"}],"version-history":[{"count":1,"href":"https:\/\/bricolos.ma\/fr\/wp-json\/wp\/v2\/pages\/196\/revisions"}],"predecessor-version":[{"id":331,"href":"https:\/\/bricolos.ma\/fr\/wp-json\/wp\/v2\/pages\/196\/revisions\/331"}],"wp:attachment":[{"href":"https:\/\/bricolos.ma\/fr\/wp-json\/wp\/v2\/media?parent=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}